{"id":1053,"date":"2021-01-28T03:35:51","date_gmt":"2021-01-28T03:35:51","guid":{"rendered":"http:\/\/javierh.sgedu.site\/?post_type=product&#038;p=1053"},"modified":"2024-04-12T14:35:58","modified_gmt":"2024-04-12T14:35:58","slug":"temps-simples-et-composes","status":"publish","type":"product","link":"https:\/\/myclass.mc\/en\/product\/temps-simples-et-composes\/","title":{"rendered":"Identifier le verbe aux temps simples et aux temps compos\u00e9s"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>Qu\u2019est-ce qu\u2019un temps simple ? Un temps compos\u00e9 ? Comment se construisent-ils ?<\/p>","protected":false},"featured_media":17125,"comment_status":"open","ping_status":"closed","template":"","meta":{"_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"default","_kad_post_title":"","_kad_post_layout":"default","_kad_post_sidebar_id":"","_kad_post_content_style":"default","_kad_post_vertical_padding":"default","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false},"product_brand":[],"product_cat":[59,55],"product_tag":[],"class_list":{"0":"post-1053","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-cm1","7":"product_cat-grammaire","9":"first","10":"instock","11":"virtual","12":"sold-individually","13":"taxable","14":"purchasable","15":"product-type-simple","16":"entry","17":"content-bg","18":"loop-entry"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Identifier le verbe aux temps simples et aux temps compos\u00e9s - Temps simples et compos\u00e9s - MyClass<\/title>\n<meta name=\"description\" content=\"Identifier le verbe aux temps simples et aux temps compos\u00e9s avec une vid\u00e9o p\u00e9dagogique et ludique, des exercices et une carte mentale.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/myclass.mc\/en\/product\/temps-simples-et-composes\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Identifier le verbe aux temps simples et aux temps compos\u00e9s - Temps simples et compos\u00e9s - MyClass\" \/>\n<meta property=\"og:description\" content=\"Identifier le verbe aux temps simples et aux temps compos\u00e9s avec une vid\u00e9o p\u00e9dagogique et ludique, des exercices et une carte mentale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/myclass.mc\/en\/product\/temps-simples-et-composes\/\" \/>\n<meta property=\"og:site_name\" content=\"MyClass\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-12T14:35:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/myclass.mc\/wp-content\/uploads\/2022\/03\/EP04.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"338\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/myclass.mc\\\/product\\\/temps-simples-et-composes\\\/\",\"url\":\"https:\\\/\\\/myclass.mc\\\/product\\\/temps-simples-et-composes\\\/\",\"name\":\"Identifier le verbe aux temps simples et aux temps compos\u00e9s - Temps simples et compos\u00e9s - MyClass\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/myclass.mc\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/myclass.mc\\\/product\\\/temps-simples-et-composes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/myclass.mc\\\/product\\\/temps-simples-et-composes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/myclass.mc\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/EP04.png\",\"datePublished\":\"2021-01-28T03:35:51+00:00\",\"dateModified\":\"2024-04-12T14:35:58+00:00\",\"description\":\"Identifier le verbe aux temps simples et aux temps compos\u00e9s avec une vid\u00e9o p\u00e9dagogique et ludique, des exercices et une carte mentale.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/myclass.mc\\\/product\\\/temps-simples-et-composes\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/myclass.mc\\\/product\\\/temps-simples-et-composes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/myclass.mc\\\/product\\\/temps-simples-et-composes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/myclass.mc\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/EP04.png\",\"contentUrl\":\"https:\\\/\\\/myclass.mc\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/EP04.png\",\"width\":600,\"height\":338},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/myclass.mc\\\/product\\\/temps-simples-et-composes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/myclass.mc\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BOUTIQUE\",\"item\":\"https:\\\/\\\/myclass.mc\\\/en\\\/boutique\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Identifier le verbe aux temps simples et aux temps compos\u00e9s\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/myclass.mc\\\/#website\",\"url\":\"https:\\\/\\\/myclass.mc\\\/\",\"name\":\"MyClass\",\"description\":\"Apprendre en s&#039;amusant !\",\"publisher\":{\"@id\":\"https:\\\/\\\/myclass.mc\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/myclass.mc\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/myclass.mc\\\/#organization\",\"name\":\"MyClass\",\"url\":\"https:\\\/\\\/myclass.mc\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/myclass.mc\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/myclass.mc\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/00HeaderLogo.png\",\"contentUrl\":\"https:\\\/\\\/myclass.mc\\\/wp-content\\\/uploads\\\/2021\\\/01\\\/00HeaderLogo.png\",\"width\":134,\"height\":63,\"caption\":\"MyClass\"},\"image\":{\"@id\":\"https:\\\/\\\/myclass.mc\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Identifier le verbe aux temps simples et aux temps compos\u00e9s - Temps simples et compos\u00e9s - MyClass","description":"Identifier le verbe aux temps simples et aux temps compos\u00e9s avec une vid\u00e9o p\u00e9dagogique et ludique, des exercices et une carte mentale.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/myclass.mc\/en\/product\/temps-simples-et-composes\/","og_locale":"en_US","og_type":"article","og_title":"Identifier le verbe aux temps simples et aux temps compos\u00e9s - Temps simples et compos\u00e9s - MyClass","og_description":"Identifier le verbe aux temps simples et aux temps compos\u00e9s avec une vid\u00e9o p\u00e9dagogique et ludique, des exercices et une carte mentale.","og_url":"https:\/\/myclass.mc\/en\/product\/temps-simples-et-composes\/","og_site_name":"MyClass","article_modified_time":"2024-04-12T14:35:58+00:00","og_image":[{"width":600,"height":338,"url":"https:\/\/myclass.mc\/wp-content\/uploads\/2022\/03\/EP04.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/myclass.mc\/product\/temps-simples-et-composes\/","url":"https:\/\/myclass.mc\/product\/temps-simples-et-composes\/","name":"Identifier le verbe aux temps simples et aux temps compos\u00e9s - Temps simples et compos\u00e9s - MyClass","isPartOf":{"@id":"https:\/\/myclass.mc\/#website"},"primaryImageOfPage":{"@id":"https:\/\/myclass.mc\/product\/temps-simples-et-composes\/#primaryimage"},"image":{"@id":"https:\/\/myclass.mc\/product\/temps-simples-et-composes\/#primaryimage"},"thumbnailUrl":"https:\/\/myclass.mc\/wp-content\/uploads\/2022\/03\/EP04.png","datePublished":"2021-01-28T03:35:51+00:00","dateModified":"2024-04-12T14:35:58+00:00","description":"Identifier le verbe aux temps simples et aux temps compos\u00e9s avec une vid\u00e9o p\u00e9dagogique et ludique, des exercices et une carte mentale.","breadcrumb":{"@id":"https:\/\/myclass.mc\/product\/temps-simples-et-composes\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/myclass.mc\/product\/temps-simples-et-composes\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/myclass.mc\/product\/temps-simples-et-composes\/#primaryimage","url":"https:\/\/myclass.mc\/wp-content\/uploads\/2022\/03\/EP04.png","contentUrl":"https:\/\/myclass.mc\/wp-content\/uploads\/2022\/03\/EP04.png","width":600,"height":338},{"@type":"BreadcrumbList","@id":"https:\/\/myclass.mc\/product\/temps-simples-et-composes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/myclass.mc\/"},{"@type":"ListItem","position":2,"name":"BOUTIQUE","item":"https:\/\/myclass.mc\/en\/boutique\/"},{"@type":"ListItem","position":3,"name":"Identifier le verbe aux temps simples et aux temps compos\u00e9s"}]},{"@type":"WebSite","@id":"https:\/\/myclass.mc\/#website","url":"https:\/\/myclass.mc\/","name":"MyClass","description":"Apprendre en s&#039;amusant !","publisher":{"@id":"https:\/\/myclass.mc\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/myclass.mc\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/myclass.mc\/#organization","name":"MyClass","url":"https:\/\/myclass.mc\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/myclass.mc\/#\/schema\/logo\/image\/","url":"https:\/\/myclass.mc\/wp-content\/uploads\/2021\/01\/00HeaderLogo.png","contentUrl":"https:\/\/myclass.mc\/wp-content\/uploads\/2021\/01\/00HeaderLogo.png","width":134,"height":63,"caption":"MyClass"},"image":{"@id":"https:\/\/myclass.mc\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/myclass.mc\/en\/wp-json\/wp\/v2\/product\/1053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/myclass.mc\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/myclass.mc\/en\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/myclass.mc\/en\/wp-json\/wp\/v2\/comments?post=1053"}],"version-history":[{"count":0,"href":"https:\/\/myclass.mc\/en\/wp-json\/wp\/v2\/product\/1053\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/myclass.mc\/en\/wp-json\/wp\/v2\/media\/17125"}],"wp:attachment":[{"href":"https:\/\/myclass.mc\/en\/wp-json\/wp\/v2\/media?parent=1053"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/myclass.mc\/en\/wp-json\/wp\/v2\/product_brand?post=1053"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/myclass.mc\/en\/wp-json\/wp\/v2\/product_cat?post=1053"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/myclass.mc\/en\/wp-json\/wp\/v2\/product_tag?post=1053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}